{"id":4228,"date":"2022-10-27T09:21:01","date_gmt":"2022-10-27T08:21:01","guid":{"rendered":"https:\/\/www.vacherin-montdor.ch\/?post_type=recette&#038;p=4228"},"modified":"2022-10-27T09:21:01","modified_gmt":"2022-10-27T08:21:01","slug":"reis-mit-zucchetti-und-vacherin","status":"publish","type":"recette","link":"https:\/\/www.vacherin-montdor.ch\/de\/recette\/reis-mit-zucchetti-und-vacherin\/","title":{"rendered":"Reis mit Zucchetti und Vacherin"},"content":{"rendered":"<p>F\u00fcr 4 Personen<\/p>\n<p><strong>Zutaten<\/strong><br \/>\n200 g Reis<br \/>\n3 kleine Zucchetti<br \/>\n50 g Butter<br \/>\n50 g Beinschinken<br \/>\n100 g Vacherin<br \/>\n1 Knoblauchzehe<br \/>\n1 Essl\u00f6ffel Zwiebeln, fein gehackt<br \/>\n7 dl Bouillon<br \/>\n1 Beutelchen Safranpulver<br \/>\n2 bis 3 Thymianzweiglein<br \/>\nSalz und Pfeffer<\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nDen Schinken in kleine St\u00fcckchen schneiden, ohne das Fett zu entfernen. In 20 g Butter in der Pfanne golden anbraten und zur Seite stellen.<br \/>\nDie Zucchetti waschen und ungesch\u00e4lt in feine Tranchen schneiden. Im Bratfett des Schinkens zwei Minuten lang auf beiden Seiten sautieren und zur Seite stellen.<br \/>\n30 g Butter in einer Pfanne schmelzen und darin die fein gehackte Zwiebel and\u00fcnsten. Den Reis beif\u00fcgen und ebenfalls leicht and\u00fcnsten. Mit der Bouillon abl\u00f6schen. 10 Minuten lang k\u00f6cheln lassen, dann die Zucchetti zuf\u00fcgen und mit Pfeffer, Safran und Thymian w\u00fcrzen.<br \/>\nSchliesslich die Schinkenst\u00fcckchen beif\u00fcgen.<br \/>\nZum Schluss den Vacherin in kleinen St\u00fcckchen dar\u00fcber verteilen und schmelzen lassen. Gut verr\u00fchren, bis der K\u00e4se sich mit der restlichen Masse verbunden hat.<\/p>\n","protected":false},"featured_media":4223,"template":"","class_list":["post-4228","recette","type-recette","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vacherin-montdor.ch\/de\/wp-json\/wp\/v2\/recette\/4228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vacherin-montdor.ch\/de\/wp-json\/wp\/v2\/recette"}],"about":[{"href":"https:\/\/www.vacherin-montdor.ch\/de\/wp-json\/wp\/v2\/types\/recette"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vacherin-montdor.ch\/de\/wp-json\/wp\/v2\/media\/4223"}],"wp:attachment":[{"href":"https:\/\/www.vacherin-montdor.ch\/de\/wp-json\/wp\/v2\/media?parent=4228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}